{"id":3183,"date":"2015-07-13T14:59:13","date_gmt":"2015-07-13T20:59:13","guid":{"rendered":"http:\/\/www.steelmax.com\/?post_type=product&#038;p=3183"},"modified":"2026-05-21T05:02:01","modified_gmt":"2026-05-21T11:02:01","slug":"d1air-pneumatic-drill-very-low-profile-drill-for-restricted-space","status":"publish","type":"product","link":"https:\/\/steelmax.com\/pt\/produto\/d1air-pneumatic-drill-very-low-profile-drill-for-restricted-space\/","title":{"rendered":"Broca pneum\u00e1tica D1 AIR ATEX"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A D1 AIR ATEX \u00e9 uma m\u00e1quina de perfura\u00e7\u00e3o pneum\u00e1tica port\u00e1til extremamente pequena para fazer furos de at\u00e9 1-3 \/ 8 \u2033 (36 mm) de di\u00e2metro em ambientes perigosos e onde o acesso ao local do furo \u00e9 restrito. O D1 AIR ATEX est\u00e1 em conformidade com o padr\u00e3o ATEX II 2 G \/ D c IIC T6 \/ T4 para equipamentos usados em ambientes perigosos.<\/p>\n<p>Uma combina\u00e7\u00e3o de acionamento pneum\u00e1tico e base magn\u00e9tica permanente elimina a necessidade de fornecimento de energia el\u00e9trica, tornando esta m\u00e1quina uma solu\u00e7\u00e3o ideal em muitos ambientes perigosos, como plataformas de petr\u00f3leo offshore, aplica\u00e7\u00f5es de minera\u00e7\u00e3o, constru\u00e7\u00e3o naval e ind\u00fastrias petroqu\u00edmicas. A D1 AIR ATEX \u00e9 uma das brocas magn\u00e9ticas de menor altura dispon\u00edveis atualmente no mercado mundial.<\/p>\n<p>RECURSOS<\/p>\n<ul>\n<li>1-3\/8\u2033 (35 mm) de di\u00e2metro x 1\u2033 (25 mm) de profundidade de corte com <a href=\"https:\/\/steelmax.com\/pt\/categoria-produto\/drilling-and-punching-machines\/annular-cutters\/\">cortadores anulares<\/a><\/li>\n<li>5\/8 \u2033 (16 mm) de di\u00e2metro com brocas inteiri\u00e7as<\/li>\n<li>Para uso em ambientes perigosos - totalmente compat\u00edvel com ATEX<\/li>\n<li>Perfil baixo para uso em espa\u00e7os com restri\u00e7\u00e3o de altura<\/li>\n<li>Acionamento pneum\u00e1tico e base magn\u00e9tica permanente<\/li>\n<\/ul>\n<blockquote><p>Este item \u00e9 enviado por frete. Ele chega em um palete e s\u00f3 pode ser enviado para um endere\u00e7o comercial.<\/p>\n<p>Entre em contato conosco para obter os acess\u00f3rios de rosqueamento dispon\u00edveis com esta furadeira.<\/p><\/blockquote>\n<div class=\"product-detail-wrapper\">\n<div class=\"product-detail\">\n<div class=\"product-detail-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/steelmax.com\/wp-content\/uploads\/2026\/03\/Shield-01.png\" alt=\"product-detail-icon\" \/><\/div>\n<p>Garantia do fabricante<\/p>\n<\/div>\n<div class=\"product-detail\">\n<div class=\"product-detail-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/steelmax.com\/wp-content\/uploads\/2026\/03\/call-02.png\" alt=\"product-detail-icon\" \/><\/div>\n<p>Suporte gratuito<\/p>\n<\/div>\n<div class=\"product-detail\">\n<div class=\"product-detail-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/steelmax.com\/wp-content\/uploads\/2026\/03\/return-02.png\" alt=\"product-detail-icon\" \/><\/div>\n<p>Devolu\u00e7\u00f5es em 30 dias<\/p>\n<\/div>\n<\/div>","protected":false},"featured_media":6970,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[256],"product_tag":[],"class_list":{"0":"post-3183","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-atex","7":"product_shipping_class-drills","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product\/3183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/comments?post=3183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/media\/6970"}],"wp:attachment":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/media?parent=3183"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product_brand?post=3183"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product_cat?post=3183"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product_tag?post=3183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a4bd3bbdb888a16edc47cf8. Config Timestamp: 2026-07-06 16:11:38 UTC, Cached Timestamp: 2026-07-15 20:33:24 UTC, Optimization Time: 19.8ms -->