{"id":13189,"date":"2024-07-11T13:51:18","date_gmt":"2024-07-11T19:51:18","guid":{"rendered":"https:\/\/steelmax.com\/?post_type=product&#038;p=13189"},"modified":"2026-05-22T04:58:11","modified_gmt":"2026-05-22T10:58:11","slug":"bm30-portable-weld-bead-shaver","status":"publish","type":"product","link":"https:\/\/steelmax.com\/pt\/produto\/bm30-portable-weld-bead-shaver\/","title":{"rendered":"Raspador de cord\u00e3o de solda port\u00e1til BM-30 WBS"},"content":{"rendered":"<p>- Fresagem de cord\u00f5es de solda de at\u00e9 1\/2\" (11 mm) de altura e 1-3\/16\" (30 mm) de largura<br \/>\n- Controle eletr\u00f4nico de velocidade entre 1800-5850 rpm<br \/>\n- Ergonomicamente projetado para aumentar o conforto durante o trabalho<br \/>\n- Cabe\u00e7ote de fresagem com 5 pe\u00e7as de pastilhas de corte index\u00e1veis de 2 lados<br \/>\n- Ajuste cont\u00ednuo da altura de fresagem<br \/>\n- Prote\u00e7\u00e3o contra sobrecarga<\/p>\n<p><script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\/\", \n  \"@type\": \"Product\", \n  \"name\": \"BM-30 WBS Portable Weld Bead Shaver\",\n  \"image\": \"https:\/\/steelmax.com\/wp-content\/uploads\/2024\/07\/BM-30-WBS-Web.png\",\n  \"description\": \"The BM30-WBS is an easy-to-use, portable, heavy-duty machine specifically designed for the removal of excess weld seams up to 1\/2? high and 1-3\/16? wide\",\n  \"brand\": {\n    \"@type\": \"Brand\",\n    \"name\": \"Steelmax Tools LLC\"\n  },\n  \"offers\": {\n    \"@type\": \"Offer\",\n    \"url\": \"https:\/\/steelmax.com\/product\/bm30-portable-weld-bead-shaver\/\",\n    \"priceCurrency\": \"USD\",\n    \"price\": \"\",\n    \"availability\": \"https:\/\/schema.org\/InStock\",\n    \"itemCondition\": \"https:\/\/schema.org\/NewCondition\"\n  }\n}\n<\/script><\/p>","protected":false},"excerpt":{"rendered":"<p>A BM30-WBS \u00e9 uma m\u00e1quina f\u00e1cil de usar, port\u00e1til e para servi\u00e7os pesados, projetada especificamente para a remo\u00e7\u00e3o de excesso de cord\u00f5es de solda de at\u00e9 1\/2\u2033 (11 mm) de altura e 1-3\/16\u2033 (30 mm) de largura. Ela fresa com efici\u00eancia uma costura de solda at\u00e9 obter uma superf\u00edcie nivelada e cont\u00ednua com o metal de base, preparando-a para pintura, revestimento ou processamento posterior.<\/p>\n<p>Equipada com um motor potente e um controle eletr\u00f4nico de velocidade que varia de 1.800 a 5.850 rpm, a BM30-WBS otimiza as condi\u00e7\u00f5es de corte para obter um desempenho superior. O cabe\u00e7ote de fresagem de faceamento rotativo garante uma opera\u00e7\u00e3o suave e uma efici\u00eancia excepcional sem criar zonas afetadas pelo calor ou distor\u00e7\u00e3o da pe\u00e7a de trabalho.<\/p>\n<p>Para maior precis\u00e3o, o BM30-WBS possui um trilho-guia com um sistema de fixa\u00e7\u00e3o magn\u00e9tica para manter uma posi\u00e7\u00e3o consistente em rela\u00e7\u00e3o \u00e0 pe\u00e7a de trabalho.<\/p>\n<h3>Caracter\u00edsticas e benef\u00edcios:<\/h3>\n<ul>\n<li><strong>Conforto e ergonomia<\/strong>: Projetado para facilitar o uso e o conforto do operador.<\/li>\n<li><strong>Motor el\u00e9trico potente<\/strong>: Oferece desempenho robusto.<\/li>\n<li><strong>Remo\u00e7\u00e3o de excesso de solda<\/strong>: Capaz de remover soldas de at\u00e9 1\/2\u2033 (11 mm) de altura e 1-3\/16\u2033 (30 mm) de largura.<\/li>\n<li><strong>Capacidade de subcota\u00e7\u00e3o<\/strong>: Cortes inferiores a uma profundidade de at\u00e9 1,5 mm.<\/li>\n<li><strong>Ajuste cont\u00ednuo da altura da fresa<\/strong>: Permite o controle preciso da altura de fresagem.<\/li>\n<li><strong>Cabe\u00e7ote de fresagem eficiente<\/strong>: Equipado com 5 pastilhas de corte index\u00e1veis de dois lados.<\/li>\n<li><strong>Controle eletr\u00f4nico de velocidade<\/strong>: Ajust\u00e1vel entre 1800-5850 rpm.<\/li>\n<li><strong>Prote\u00e7\u00e3o contra sobrecarga<\/strong>: Garante durabilidade e seguran\u00e7a.<\/li>\n<\/ul>","protected":false},"featured_media":13190,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[254,211,213],"product_tag":[316],"class_list":{"0":"post-13189","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-automatic","7":"product_cat-plate-pipe-beveling","8":"product_cat-plate-bevelers","9":"product_tag-beveling","11":"first","12":"instock","13":"featured","14":"taxable","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product\/13189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/comments?post=13189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/media\/13190"}],"wp:attachment":[{"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/media?parent=13189"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product_brand?post=13189"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product_cat?post=13189"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steelmax.com\/pt\/wp-json\/wp\/v2\/product_tag?post=13189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a4bd3bbdb888a16edc47cf8. Config Timestamp: 2026-07-06 16:11:38 UTC, Cached Timestamp: 2026-07-15 22:54:16 UTC, Optimization Time: 20.19ms -->